{"id":14034,"date":"2021-12-27T13:02:10","date_gmt":"2021-12-27T11:02:10","guid":{"rendered":"https:\/\/studygo.com\/nl\/?page_id=14034"},"modified":"2025-03-25T16:24:37","modified_gmt":"2025-03-25T16:24:37","slug":"vragen","status":"publish","type":"page","link":"https:\/\/studygo.com\/nl\/oefenen\/functies\/vragen\/","title":{"rendered":"Vragen"},"content":{"rendered":"<section class=\"header-block detail-header \" style=\"color: #ffffff\">\n        <div class=\"header-block-bg\" style=\"background-color: #652ea3;\">\n                    <\/div>\n        <div class=\"carrier\">\n            <div class=\"tier content-row\">\n                <div class=\"col m-6 m-offset-0 last-m header-img-col \" >\n                                                                <div class=\"header-img  \">\n                                                                                                                            <img decoding=\"async\" class=\"img\" src=\"https:\/\/www-media.studygo.com\/wp-content\/uploads\/2021\/10\/QA-Couple-800x534.png\"\n                                    alt=\"forum WRTS\">\n                                                    <\/div>\n                                    <\/div>\n                <div class=\"col m-6\">\n                    <div class=\"header-info\">\n                        <h1 class=\"page-title animated \">Vragen<\/h1>                        <div class=\"section-desc animated \">\n                            <p class=\"section-desc\">\n                                    <p class=\"section-desc\">Heb je een vraag over de lesstof? Of kom je ergens niet uit? Zoek dan in het vragenoverzicht of jouw vraag daarbij staat. Niks te vinden? Stel dan je eigen vraag en krijg antwoord van andere leerlingen of van \u00e9\u00e9n van onze tutors.<\/p>\n\n                            <\/p>\n                            <div class=\"knob-block-row\">\n                                            <div class=\"knob-block\">\n                <a href=\"http:\/\/studygo.com\/nl\/learn\/questions\/overview\"\n                   id=\"vragen_header-4241_text-button\"\n                   class=\"simple-knob blue with-icon\"\n                   aria-label=\"Zoek of stel je vraag\"\n                    target=\"_blank\">\n                    <span class=\"text\">Zoek of stel je vraag<\/span>\n                    <span class=\"icon icon-arrow-large-right\"><\/span>\n                <\/a>\n            <\/div>\n                                                                    <\/div>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/section><section class=\"page-section media-block reverse\"\n    >\n    <div class=\"carrier\">\n        <div class=\"tier middle-m content-row\">\n            <div class=\"col m-6 media-preview-col \">\n                                            <div class=\"media-preview img-fit\"\n                     style=\"background-image: url(https:\/\/www-media.studygo.com\/wp-content\/uploads\/2021\/12\/q_and_a-800x533.png)\"\n                     aria-hidden=\"true\">\n                                                        <\/div>\n                                        <\/div>\n            <div class=\"media-info-col col m-5 m-offset-1\">\n                <div class=\"media-info\">\n                                        <h2 class=\"section-title animated\"><strong><strong><strong>Verdien punten door te antwoorden<\/strong><\/strong><\/strong><\/h2>\n                    <div class=\"section-desc animated\">\n                            <p class=\"section-desc\">Ga voor het hoogste level! Help anderen door vragen te beantwoorden en verdien punten. Hoe meer punten, hoe hoger je level. Als je antwoord van uitstekende kwaliteit is, kan deze worden uitgelicht door een tutor. En dat schiet lekker op in de punten!<\/p>\n\n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section><section class=\"page-section media-block white-section\"\n    >\n    <div class=\"carrier\">\n        <div class=\"tier middle-m content-row\">\n            <div class=\"col m-6 media-preview-col \">\n                                            <div class=\"media-preview img-fit\"\n                     style=\"background-image: url(https:\/\/www-media.studygo.com\/wp-content\/uploads\/2021\/04\/chatten-met-tutors-e1618904530405-800x533.png)\"\n                     role=\"img\" aria-label=\"live chatten met docenten\">\n                                                        <\/div>\n                                        <\/div>\n            <div class=\"media-info-col col m-5 m-offset-1\">\n                <div class=\"media-info\">\n                                        <h2 class=\"section-title animated\"><strong><strong><strong>Antwoorden van tutors<\/strong><\/strong><\/strong><\/h2>\n                    <div class=\"section-desc animated\">\n                            <p class=\"section-desc\">Wil je zeker weten dat het antwoord wat je krijgt goed is? Dan kun je, als je in de onderbouw zit en een Premium of Pro abonnement hebt, antwoord krijgen van \u00e9\u00e9n van onze tutors. Hiermee kun je ook de antwoorden zien die tutors hebben gegeven op andere vragen.<\/p>\n\n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section><section class=\"title-block\"\n    >\n    <div class=\"carrier\">\n        <div class=\"tier center-xs\">\n            <div class=\"col s-10 l-8 animated\">\n                <h2 class=\"section-title\">Probeer StudyGo zelf<\/h2>\n                            <\/div>\n            <div class=\"col s-8 l-6 animated\">\n                    <p class=\"section-desc\"><br><\/p>\n\n                            <\/div>\n        <\/div>\n    <\/div>\n<\/section><section class=\"page-section order-block\">\n    <div class=\"carrier\">\n                            <div class=\"tier\">\n                                    <div class=\"col m-6 l-4 m-offset-3 l-offset-4\">\n                        <div class=\"image-wrap\">\n                            <img decoding=\"async\" class=\"image\" src=\"https:\/\/www-media.studygo.com\/wp-content\/uploads\/2023\/02\/Laptop-w-Subjects-e1683619233429-360x240.png\" alt=\"Start nu\">\n                        <\/div>\n                    <\/div>\n                                <div class=\"col m-8 l-6 m-offset-2 l-offset-3\">\n                                            <p class=\"section-desc order-desc\">Volg onbeperkt online bijles, maak oefentoetsen, oefen je woordjes of bekijk uitlegvideo\u2019s. Zo haal je hogere cijfers voor je toetsen.<\/p>\n                                        <div class=\"knob-block\">\n                        <a href=\"https:\/\/studygo.com\/nl\/learn\/sign-up?last_page_slug=%252Fnl%252Fwp-json%252Fwp%252Fv2%252Fpages%252F14034\"\n                           id=\"vragen_order-4321_order-button\"\n                           class=\"knob order-knob large\">\n                            <span class=\"visual\">Gratis registreren<\/span>\n                        <\/a>\n                    <\/div>\n                                                                                <\/div>\n            <\/div>\n            <\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"author":8,"featured_media":0,"parent":26703,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-14034","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Oefenvragen \u2013 Test en verbeter je kennis | StudyGo<\/title>\n<meta name=\"description\" content=\"Stel vragen en oefen met interactieve opdrachten. Begrijp moeilijke onderwerpen beter en leer slimmer!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/studygo.com\/nl\/oefenen\/functies\/vragen\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oefenvragen \u2013 Test en verbeter je kennis | StudyGo\" \/>\n<meta property=\"og:description\" content=\"Stel vragen en oefen met interactieve opdrachten. Begrijp moeilijke onderwerpen beter en leer slimmer!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/studygo.com\/nl\/oefenen\/functies\/vragen\/\" \/>\n<meta property=\"og:site_name\" content=\"StudyGo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/studygoNL\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-25T16:24:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www-media.studygo.com\/wp-content\/uploads\/2022\/05\/forum.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2400\" \/>\n\t<meta property=\"og:image:height\" content=\"1260\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/studygo.com\\\/oefenen\\\/functies\\\/vragen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/studygo.com\\\/oefenen\\\/functies\\\/vragen\\\/\"},\"author\":{\"name\":\"Daan Smith\",\"@id\":\"https:\\\/\\\/studygo.com\\\/#\\\/schema\\\/person\\\/69cc66a4a196cc104096bc58b9267c45\"},\"headline\":\"Vragen\",\"datePublished\":\"2021-12-27T11:02:10+00:00\",\"dateModified\":\"2025-03-25T16:24:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/studygo.com\\\/oefenen\\\/functies\\\/vragen\\\/\"},\"wordCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/studygo.com\\\/#organization\"},\"inLanguage\":\"nl-NL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/studygo.com\\\/oefenen\\\/functies\\\/vragen\\\/\",\"url\":\"https:\\\/\\\/studygo.com\\\/oefenen\\\/functies\\\/vragen\\\/\",\"name\":\"Oefenvragen \u2013 Test en verbeter je kennis | StudyGo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/studygo.com\\\/#website\"},\"datePublished\":\"2021-12-27T11:02:10+00:00\",\"dateModified\":\"2025-03-25T16:24:37+00:00\",\"description\":\"Stel vragen en oefen met interactieve opdrachten. Begrijp moeilijke onderwerpen beter en leer slimmer!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/studygo.com\\\/oefenen\\\/functies\\\/vragen\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/studygo.com\\\/oefenen\\\/functies\\\/vragen\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/studygo.com\\\/oefenen\\\/functies\\\/vragen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/studygo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Oefenen\",\"item\":\"https:\\\/\\\/studygo.com\\\/oefenen\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Functies (INT)\",\"item\":\"https:\\\/\\\/studygo.com\\\/oefenen\\\/functies\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Vragen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/studygo.com\\\/#website\",\"url\":\"https:\\\/\\\/studygo.com\\\/\",\"name\":\"StudyGo\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/studygo.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/studygo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/studygo.com\\\/#organization\",\"name\":\"StudyGo\",\"url\":\"https:\\\/\\\/studygo.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/studygo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www-media.studygo.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/studygo-logo.png\",\"contentUrl\":\"https:\\\/\\\/www-media.studygo.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/studygo-logo.png\",\"width\":1244,\"height\":858,\"caption\":\"StudyGo\"},\"image\":{\"@id\":\"https:\\\/\\\/studygo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/studygoNL\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@StudyGoNL\\\/videos\",\"https:\\\/\\\/www.instagram.com\\\/studygonl\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/studygo.com\\\/#\\\/schema\\\/person\\\/69cc66a4a196cc104096bc58b9267c45\",\"name\":\"Daan Smith\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fc0839328d88751627f34ab4d5e5b2de3c02438c29e9a35ae8ba71a67cf4cc3e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fc0839328d88751627f34ab4d5e5b2de3c02438c29e9a35ae8ba71a67cf4cc3e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fc0839328d88751627f34ab4d5e5b2de3c02438c29e9a35ae8ba71a67cf4cc3e?s=96&d=mm&r=g\",\"caption\":\"Daan Smith\"},\"url\":\"https:\\\/\\\/studygo.com\\\/nl\\\/author\\\/daan\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Oefenvragen \u2013 Test en verbeter je kennis | StudyGo","description":"Stel vragen en oefen met interactieve opdrachten. Begrijp moeilijke onderwerpen beter en leer slimmer!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/studygo.com\/nl\/oefenen\/functies\/vragen\/","og_locale":"nl_NL","og_type":"article","og_title":"Oefenvragen \u2013 Test en verbeter je kennis | StudyGo","og_description":"Stel vragen en oefen met interactieve opdrachten. Begrijp moeilijke onderwerpen beter en leer slimmer!","og_url":"https:\/\/studygo.com\/nl\/oefenen\/functies\/vragen\/","og_site_name":"StudyGo","article_publisher":"https:\/\/www.facebook.com\/studygoNL\/","article_modified_time":"2025-03-25T16:24:37+00:00","og_image":[{"width":2400,"height":1260,"url":"https:\/\/www-media.studygo.com\/wp-content\/uploads\/2022\/05\/forum.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/studygo.com\/oefenen\/functies\/vragen\/#article","isPartOf":{"@id":"https:\/\/studygo.com\/oefenen\/functies\/vragen\/"},"author":{"name":"Daan Smith","@id":"https:\/\/studygo.com\/#\/schema\/person\/69cc66a4a196cc104096bc58b9267c45"},"headline":"Vragen","datePublished":"2021-12-27T11:02:10+00:00","dateModified":"2025-03-25T16:24:37+00:00","mainEntityOfPage":{"@id":"https:\/\/studygo.com\/oefenen\/functies\/vragen\/"},"wordCount":1,"publisher":{"@id":"https:\/\/studygo.com\/#organization"},"inLanguage":"nl-NL"},{"@type":"WebPage","@id":"https:\/\/studygo.com\/oefenen\/functies\/vragen\/","url":"https:\/\/studygo.com\/oefenen\/functies\/vragen\/","name":"Oefenvragen \u2013 Test en verbeter je kennis | StudyGo","isPartOf":{"@id":"https:\/\/studygo.com\/#website"},"datePublished":"2021-12-27T11:02:10+00:00","dateModified":"2025-03-25T16:24:37+00:00","description":"Stel vragen en oefen met interactieve opdrachten. Begrijp moeilijke onderwerpen beter en leer slimmer!","breadcrumb":{"@id":"https:\/\/studygo.com\/oefenen\/functies\/vragen\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/studygo.com\/oefenen\/functies\/vragen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/studygo.com\/oefenen\/functies\/vragen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/studygo.com\/"},{"@type":"ListItem","position":2,"name":"Oefenen","item":"https:\/\/studygo.com\/oefenen\/"},{"@type":"ListItem","position":3,"name":"Functies (INT)","item":"https:\/\/studygo.com\/oefenen\/functies\/"},{"@type":"ListItem","position":4,"name":"Vragen"}]},{"@type":"WebSite","@id":"https:\/\/studygo.com\/#website","url":"https:\/\/studygo.com\/","name":"StudyGo","description":"","publisher":{"@id":"https:\/\/studygo.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/studygo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/studygo.com\/#organization","name":"StudyGo","url":"https:\/\/studygo.com\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/studygo.com\/#\/schema\/logo\/image\/","url":"https:\/\/www-media.studygo.com\/wp-content\/uploads\/2025\/06\/studygo-logo.png","contentUrl":"https:\/\/www-media.studygo.com\/wp-content\/uploads\/2025\/06\/studygo-logo.png","width":1244,"height":858,"caption":"StudyGo"},"image":{"@id":"https:\/\/studygo.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/studygoNL\/","https:\/\/www.youtube.com\/@StudyGoNL\/videos","https:\/\/www.instagram.com\/studygonl"]},{"@type":"Person","@id":"https:\/\/studygo.com\/#\/schema\/person\/69cc66a4a196cc104096bc58b9267c45","name":"Daan Smith","image":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/secure.gravatar.com\/avatar\/fc0839328d88751627f34ab4d5e5b2de3c02438c29e9a35ae8ba71a67cf4cc3e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fc0839328d88751627f34ab4d5e5b2de3c02438c29e9a35ae8ba71a67cf4cc3e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fc0839328d88751627f34ab4d5e5b2de3c02438c29e9a35ae8ba71a67cf4cc3e?s=96&d=mm&r=g","caption":"Daan Smith"},"url":"https:\/\/studygo.com\/nl\/author\/daan\/"}]}},"_links":{"self":[{"href":"https:\/\/studygo.com\/nl\/wp-json\/wp\/v2\/pages\/14034","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/studygo.com\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/studygo.com\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/studygo.com\/nl\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/studygo.com\/nl\/wp-json\/wp\/v2\/comments?post=14034"}],"version-history":[{"count":12,"href":"https:\/\/studygo.com\/nl\/wp-json\/wp\/v2\/pages\/14034\/revisions"}],"predecessor-version":[{"id":27158,"href":"https:\/\/studygo.com\/nl\/wp-json\/wp\/v2\/pages\/14034\/revisions\/27158"}],"up":[{"embeddable":true,"href":"https:\/\/studygo.com\/nl\/wp-json\/wp\/v2\/pages\/26703"}],"wp:attachment":[{"href":"https:\/\/studygo.com\/nl\/wp-json\/wp\/v2\/media?parent=14034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}